{"id":23812,"date":"2026-03-01T09:29:22","date_gmt":"2026-03-01T09:29:22","guid":{"rendered":"https:\/\/fajador.com\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/"},"modified":"2026-03-01T09:54:23","modified_gmt":"2026-03-01T09:54:23","slug":"ricardo-celis-video-adonde-va-el-dinero-del-boxeo","status":"publish","type":"post","link":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/","title":{"rendered":"Ricardo Celis (V\u00eddeo): \u00ab\u00bfAd\u00f3nde va el dinero del boxeo?\u00bb"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Ricardo Celis  <\/h3>\n\n<p class=\"wp-block-paragraph\">En el episodio n\u00ba 73 de <a href=\"https:\/\/fajador.com\/es\/regreso-de-combate-global-en-esta-esquina-live\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abEn Esta Esquina<\/a>\u00ab, el presentador <a href=\"https:\/\/www.instagram.com\/carlos_baltazar85\/?igsh=dXc0emdpdDJxNHFi#\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Baltazar <\/a>entrevist\u00f3 al veterano comentarista deportivo <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ricardo_Celis\" target=\"_blank\" rel=\"noreferrer noopener\">Ricardo Celis<\/a>. Transmitiendo desde los estudios <a href=\"https:\/\/www.estrellatv.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">de EstrellaTV<\/a>, abordaron una pregunta pol\u00e9mica. En concreto, preguntaron: \u00bfa d\u00f3nde va a parar el dinero del Fondo de Boxeadores Jos\u00e9 Sulaim\u00e1n?  <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfUn legado de apoyo o un misterio financiero?<\/h3>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-1024x572.webp\" alt=\"\" class=\"wp-image-23815\" style=\"aspect-ratio:1.7902423075525848;width:488px;height:auto\" srcset=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-1024x572.webp 1024w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-300x167.webp 300w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-768x429.webp 768w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-1536x857.webp 1536w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-2048x1143.webp 2048w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-860x480.webp 860w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_nouscfnouscfnous-760x424.webp 760w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Una interpretaci\u00f3n art\u00edstica basada en im\u00e1genes facilitadas por cortes\u00eda del CMB.<\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">El Fondo de Boxeadores Jos\u00e9 Sulaim\u00e1n opera a trav\u00e9s de la Fundaci\u00f3n Comunitaria de Nevada<a href=\"https:\/\/www.nevadacf.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">(NCF<\/a>). Esta organizaci\u00f3n independiente sin \u00e1nimo de lucro revisa las solicitudes y coordina los pagos. En \u00faltima instancia, su objetivo principal es gestionar las operaciones con integridad y equidad para los atletas.  <\/p>\n\n<h3 class=\"wp-block-heading\">Grandes donaciones y galas repletas de estrellas<\/h3>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-1024x683.webp\" alt=\"\" class=\"wp-image-23816\" style=\"aspect-ratio:1.4992850406157778;width:620px;height:auto\" srcset=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-1024x683.webp 1024w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-300x200.webp 300w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-768x512.webp 768w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-1536x1024.webp 1536w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-330x220.webp 330w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-420x280.webp 420w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-615x410.webp 615w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-860x573.webp 860w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3-760x507.webp 760w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-3.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Imagen cortes\u00eda del Consejo Mundial de Boxeo (CMB)<\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">En <a href=\"https:\/\/wbcboxing.com\/en\/el-legado-de-don-jose-sulaiman-vive-a-traves-del-fondo-de-boxeadores\/#:~:text=The%20Fund%E2%80%99s%20strength,musician%20Carlos%20Santana.\" target=\"_blank\" rel=\"noreferrer noopener\">2014<\/a>, el CMB y<a href=\"https:\/\/www.fundaciontelmextelcel.org\/ring-telmex-telcel\" target=\"_blank\" rel=\"noreferrer noopener\"> la Fundaci\u00f3n Ring Telmex-Telcel<\/a> llegaron a un acuerdo. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Carlos_Slim\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Slim<\/a> se comprometi\u00f3 a aportar 150.000 d\u00f3lares anuales durante cinco a\u00f1os, un total de 750.000 d\u00f3lares. Adem\u00e1s, el poder del fondo creci\u00f3 en 2019. Una exitosa Cena de Gala <a href=\"https:\/\/www.hublot.com\/en-us\/event\/hublot-and-wbc-team-legendary-night-champions\" target=\"_blank\" rel=\"noreferrer noopener\">Hublot\/WBC<\/a> recaud\u00f3 1,2 millones de d\u00f3lares adicionales.  <\/p>\n\n<h3 class=\"wp-block-heading\">Los campeones dan un paso al frente<\/h3>\n\n<p class=\"wp-block-paragraph\">Este glamuroso evento cont\u00f3 con la presencia de la realeza del boxeo. Asistieron leyendas como<a href=\"https:\/\/en.wikipedia.org\/wiki\/Mike_Tyson\" target=\"_blank\" rel=\"noreferrer noopener\"> Mike Tyson<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Sugar_Ray_Leonard\" target=\"_blank\" rel=\"noreferrer noopener\">Sugar Ray Leonard<\/a> y <a href=\"https:\/\/en.wikipedia.org\/wiki\/Oscar_De_La_Hoya\" target=\"_blank\" rel=\"noreferrer noopener\">Oscar De La Hoya<\/a>. En 12 a\u00f1os, la NCF ha concedido m\u00e1s de 2 millones de d\u00f3lares a luchadores de todo el mundo. Sin embargo, sigue habiendo cuestiones cruciales en relaci\u00f3n con la transparencia financiera.   <\/p>\n\n<h3 class=\"wp-block-heading\">La tr\u00e1gica historia de Magomed Abdusalamov<\/h3>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-1024x768.webp\" alt=\"\" class=\"wp-image-23817\" style=\"width:464px;height:auto\" srcset=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-1024x768.webp 1024w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-300x225.webp 300w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-768x576.webp 768w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-1536x1151.webp 1536w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-860x645.webp 860w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4-760x570.webp 760w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/image-4.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><i>Imagen de <\/i>Magomed \u00abEl Mago\u00bb Abdusalamov. Imagen cortes\u00eda del Consejo Mundial de Boxeo (CMB)<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Uno de los casos m\u00e1s impactantes apoyados por el fondo es el de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Magomed_Abdusalamov\" target=\"_blank\" rel=\"noreferrer noopener\">Magomed \u00abEl Mago\u00bb Abdusalamov<\/a>. Nacido en Rusia en los a\u00f1os 80, Magomed era un artista del nocaut invicto. Por desgracia, durante su decimonoveno combate, el 2 de noviembre de 2013, le sobrevino la tragedia. Sufri\u00f3 graves lesiones cerebrales y perdi\u00f3 la mitad de sus movimientos corporales.   <\/p>\n\n<h3 class=\"wp-block-heading\">Luchar por la justicia fuera del ring<\/h3>\n\n<p class=\"wp-block-paragraph\">Tras la pelea, su familia denunci\u00f3 que se le neg\u00f3 atenci\u00f3n m\u00e9dica adecuada e inmediata. Mientras su leal esposa cuidaba de \u00e9l y de sus hijos, sus deudas m\u00e9dicas se dispararon. Sorprendentemente, s\u00f3lo hab\u00eda ganado 40.000 d\u00f3lares por aquel fat\u00eddico combate que cambi\u00f3 su vida. <a href=\"https:\/\/wbcboxing.com\/en\/el-legado-de-don-jose-sulaiman-vive-a-traves-del-fondo-de-boxeadores\/#:~:text=However%2C%20in%20his%2019th%20bout%2C%20everything%20changed\" target=\"_blank\" rel=\"noreferrer noopener\">Seg\u00fan el<\/a> fondo, el Fondo de Boxeadores Jos\u00e9 Sulaim\u00e1n intervino en esta \u00e9poca oscura.   <\/p>\n\n<h3 class=\"wp-block-heading\">Salvavidas financiero y victoria legal<\/h3>\n\n<p class=\"wp-block-paragraph\">El fondo proporcion\u00f3 una ayuda econ\u00f3mica crucial entre 2014 y 2016. Finalmente, la familia de Magomed \u00abnoque\u00f3\u00bb al Estado de Nueva York en los tribunales. Ganaron una enorme demanda por negligencia de 22 millones de d\u00f3lares. Este importante acuerdo garantiza su atenci\u00f3n m\u00e9dica continua. El temprano apoyo del fondo sigue siendo un orgulloso testimonio de su misi\u00f3n caritativa.    <\/p>\n\n<h3 class=\"wp-block-heading\">Ricardo Celis exige verdadera transparencia<\/h3>\n\n<p class=\"wp-block-paragraph\">Sin embargo, la pregunta central de Ricardo Celis sigue en pie. Pregunta: \u00bfllega realmente el dinero al fondo si ning\u00fan<a href=\"https:\/\/projects.propublica.org\/nonprofits\/organizations\/980048605\" target=\"_blank\" rel=\"noreferrer noopener\"> documento fiscal <\/a>legal prueba que las aportaciones adicionales del CMB van al fondo, as\u00ed que ad\u00f3nde va ese dinero? Est\u00e1 claro que a <a href=\"https:\/\/www.instagram.com\/celisdeportes\/?hl=en\" target=\"_blank\" rel=\"noreferrer noopener\">Ricardo Celis <\/a>no le resulta extra\u00f1o plantear preguntas dif\u00edciles y necesarias. El dos veces ganador <a href=\"https:\/\/en.wikipedia.org\/wiki\/Emmy_Awards\" target=\"_blank\" rel=\"noreferrer noopener\">del Emmy<\/a> ha cubierto eventos deportivos de primera durante d\u00e9cadas.   <\/p>\n\n<h3 class=\"wp-block-heading\">Una voz veterana en las retransmisiones deportivas<\/h3>\n\n<p class=\"wp-block-paragraph\">Nacido en M\u00e9xico en 1962, Celis ha construido una carrera incre\u00edble. Desde Univisi\u00f3n hasta <a href=\"https:\/\/simple.wikipedia.org\/wiki\/HBO_(Latin_American_TV_channel)\" target=\"_blank\" rel=\"noreferrer noopener\">HBO Latinoam\u00e9rica<\/a>, Celis ha retransmitido con confianza algunos de los combates de boxeo m\u00e1s importantes. Su estelar carrera como locutor incluye tambi\u00e9n la cobertura de la Super Bowl, las Series Mundiales y los Juegos Ol\u00edmpicos. Por lo tanto, cuando este respetado veterano cuestiona una organizaci\u00f3n ben\u00e9fica, la gente escucha.   <\/p>\n\n<h3 class=\"wp-block-heading\">Responsabilizar a la industria hoy<\/h3>\n\n<p class=\"wp-block-paragraph\">En la actualidad, Celis contin\u00faa su fenomenal labor como presentador deportivo. Tras haber trabajado con Telemundo y Time Warner Cable Deportes, su integridad period\u00edstica sigue siendo inigualable. En \u00faltima instancia, su entrevista exclusiva en<a href=\"https:\/\/fajador.com\/video-armando-toro-resendiz-i-going-all-in\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abEn Esta Esquina<\/a>\u00bb nos recuerda que defender a los luchadores requiere tanto una pasi\u00f3n inquebrantable como una estricta responsabilidad financiera por parte de las grandes organizaciones deportivas.   Mira el EP <a href=\"https:\/\/www.instagram.com\/reel\/DVVhqbIAcn7\/?igsh=Ym40MGh3MDF4MWI1\" target=\"_blank\" rel=\"noreferrer noopener\">#073<\/a> en \u00abEn Esta Esquina\u00bb en el escenario de Combate Global en Burbank, CA \u00a1Ahora!  <\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.instagram.com\/reel\/DVVhqbIAcn7\/?igsh=Ym40MGh3MDF4MWI1\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"546\" src=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-1024x546.webp\" alt=\"\" class=\"wp-image-23810\" srcset=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-1024x546.webp 1024w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-300x160.webp 300w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-768x409.webp 768w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-1536x819.webp 1536w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-860x458.webp 860w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73-760x405.webp 760w, https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/IG-EP73.webp 1974w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Celis En el episodio n\u00ba 73 de \u00abEn Esta Esquina\u00ab, el presentador Carlos Baltazar entrevist\u00f3 al veterano comentarista deportivo Ricardo Celis. Transmitiendo desde los estudios de EstrellaTV, abordaron una pregunta pol\u00e9mica. En concreto, preguntaron: \u00bfa d\u00f3nde va a parar el dinero del Fondo de Boxeadores Jos\u00e9 Sulaim\u00e1n? \u00bfUn legado de apoyo o un misterio [&hellip;]<\/p>\n","protected":false},"author":870,"featured_media":23813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAowwMa9DA:productID":"","footnotes":""},"categories":[140,159,227,133,162],"tags":[299,2268],"class_list":["post-23812","post","type-post","status-publish","format-standard","has-post-thumbnail","category-boxeo","category-mma-es","category-noticias","category-sin-categorizar","category-video-es","tag-boxeo","tag-noticias-es"],"yoast_head":"\n<title>Ricardo Celis (V\u00eddeo): &quot;\u00bfAd\u00f3nde va el dinero del boxeo?&quot; - Fajador<\/title>\n<meta name=\"description\" content=\"Fajador.com - \u00bfAd\u00f3nde va el dinero del boxeo del CMB? El veterano comentarista deportivo Ricardo Celis exige respuestas y transparencia financiera.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricardo Celis (V\u00eddeo): &quot;\u00bfAd\u00f3nde va el dinero del boxeo?&quot; - Fajador\" \/>\n<meta property=\"og:description\" content=\"Fajador.com - \u00bfAd\u00f3nde va el dinero del boxeo del CMB? El veterano comentarista deportivo Ricardo Celis exige respuestas y transparencia financiera.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fajador\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/p\/Fajador-61566924322340\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-01T09:29:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-01T09:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Ricardo-EP73-Thumbnail-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Fajador Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FajadorMedia\" \/>\n<meta name=\"twitter:site\" content=\"@FajadorMedia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fajador Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/\"},\"author\":{\"name\":\"Fajador Noticias\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#\\\/schema\\\/person\\\/e9db63ee9447a5ddb11c95253ed203f3\"},\"headline\":\"Ricardo Celis (V\u00eddeo): \u00ab\u00bfAd\u00f3nde va el dinero del boxeo?\u00bb\",\"datePublished\":\"2026-03-01T09:29:22+00:00\",\"dateModified\":\"2026-03-01T09:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/\"},\"wordCount\":729,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fajador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricardo-EP73-Thumbnail-scaled.webp\",\"keywords\":[\"Boxeo\",\"Noticias\"],\"articleSection\":[\"Boxeo\",\"MMA\",\"Noticias\",\"Sin categorizar\",\"Video\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/\",\"url\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/\",\"name\":\"Ricardo Celis (V\u00eddeo): \\\"\u00bfAd\u00f3nde va el dinero del boxeo?\\\" - Fajador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fajador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricardo-EP73-Thumbnail-scaled.webp\",\"datePublished\":\"2026-03-01T09:29:22+00:00\",\"dateModified\":\"2026-03-01T09:54:23+00:00\",\"description\":\"Fajador.com - \u00bfAd\u00f3nde va el dinero del boxeo del CMB? El veterano comentarista deportivo Ricardo Celis exige respuestas y transparencia financiera.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fajador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricardo-EP73-Thumbnail-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/fajador.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ricardo-EP73-Thumbnail-scaled.webp\",\"width\":2560,\"height\":1388,\"caption\":\"Imagen del Podcast \\\"En Esta Esquina\\\" con Carlos Baltazar (izquierda) y el veterano comentarista deportivo de TV Ricardo Celis en el Episodio #73 | Fajador Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fajador.com\\\/es\\\/inicio-incumplimiento\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricardo Celis (V\u00eddeo): \u00ab\u00bfAd\u00f3nde va el dinero del boxeo?\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fajador.com\\\/es\\\/\",\"name\":\"Fajador\",\"description\":\"MMAFighting.com, MMAJunkie.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fajador.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#organization\",\"name\":\"Fajador\",\"url\":\"https:\\\/\\\/fajador.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fajador.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/download.png\",\"contentUrl\":\"https:\\\/\\\/fajador.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/download.png\",\"width\":1949,\"height\":889,\"caption\":\"Fajador\"},\"image\":{\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/FajadorMedia\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJTdJHPyJbfRNKOeCd_O-Bw\",\"https:\\\/\\\/www.instagram.com\\\/fajadormedia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fajador.com\\\/es\\\/#\\\/schema\\\/person\\\/e9db63ee9447a5ddb11c95253ed203f3\",\"name\":\"Fajador Noticias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba5d64466b624cbe3591dc01ffc4978fdb6859827f3e152ee9a8625fd00a2cea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba5d64466b624cbe3591dc01ffc4978fdb6859827f3e152ee9a8625fd00a2cea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba5d64466b624cbe3591dc01ffc4978fdb6859827f3e152ee9a8625fd00a2cea?s=96&d=mm&r=g\",\"caption\":\"Fajador Noticias\"},\"sameAs\":[\"http:\\\/\\\/fajador.com\",\"https:\\\/\\\/www.facebook.com\\\/p\\\/Fajador-61566924322340\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fajadormedia\\\/?hl=en\"],\"url\":\"https:\\\/\\\/fajador.com\\\/es\\\/author\\\/fajador-noticias\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"Ricardo Celis (V\u00eddeo): \"\u00bfAd\u00f3nde va el dinero del boxeo?\" - Fajador","description":"Fajador.com - \u00bfAd\u00f3nde va el dinero del boxeo del CMB? El veterano comentarista deportivo Ricardo Celis exige respuestas y transparencia financiera.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/","og_locale":"es_ES","og_type":"article","og_title":"Ricardo Celis (V\u00eddeo): \"\u00bfAd\u00f3nde va el dinero del boxeo?\" - Fajador","og_description":"Fajador.com - \u00bfAd\u00f3nde va el dinero del boxeo del CMB? El veterano comentarista deportivo Ricardo Celis exige respuestas y transparencia financiera.","og_url":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/","og_site_name":"Fajador","article_author":"https:\/\/www.facebook.com\/p\/Fajador-61566924322340\/","article_published_time":"2026-03-01T09:29:22+00:00","article_modified_time":"2026-03-01T09:54:23+00:00","og_image":[{"width":2560,"height":1388,"url":"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Ricardo-EP73-Thumbnail-scaled.webp","type":"image\/webp"}],"author":"Fajador Noticias","twitter_card":"summary_large_image","twitter_creator":"@FajadorMedia","twitter_site":"@FajadorMedia","twitter_misc":{"Escrito por":"Fajador Noticias","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#article","isPartOf":{"@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/"},"author":{"name":"Fajador Noticias","@id":"https:\/\/fajador.com\/es\/#\/schema\/person\/e9db63ee9447a5ddb11c95253ed203f3"},"headline":"Ricardo Celis (V\u00eddeo): \u00ab\u00bfAd\u00f3nde va el dinero del boxeo?\u00bb","datePublished":"2026-03-01T09:29:22+00:00","dateModified":"2026-03-01T09:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/"},"wordCount":729,"commentCount":0,"publisher":{"@id":"https:\/\/fajador.com\/es\/#organization"},"image":{"@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#primaryimage"},"thumbnailUrl":"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Ricardo-EP73-Thumbnail-scaled.webp","keywords":["Boxeo","Noticias"],"articleSection":["Boxeo","MMA","Noticias","Sin categorizar","Video"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/","url":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/","name":"Ricardo Celis (V\u00eddeo): \"\u00bfAd\u00f3nde va el dinero del boxeo?\" - Fajador","isPartOf":{"@id":"https:\/\/fajador.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#primaryimage"},"image":{"@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#primaryimage"},"thumbnailUrl":"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Ricardo-EP73-Thumbnail-scaled.webp","datePublished":"2026-03-01T09:29:22+00:00","dateModified":"2026-03-01T09:54:23+00:00","description":"Fajador.com - \u00bfAd\u00f3nde va el dinero del boxeo del CMB? El veterano comentarista deportivo Ricardo Celis exige respuestas y transparencia financiera.","breadcrumb":{"@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#primaryimage","url":"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Ricardo-EP73-Thumbnail-scaled.webp","contentUrl":"https:\/\/fajador.com\/wp-content\/uploads\/2026\/03\/Ricardo-EP73-Thumbnail-scaled.webp","width":2560,"height":1388,"caption":"Imagen del Podcast \"En Esta Esquina\" con Carlos Baltazar (izquierda) y el veterano comentarista deportivo de TV Ricardo Celis en el Episodio #73 | Fajador Media"},{"@type":"BreadcrumbList","@id":"https:\/\/fajador.com\/es\/ricardo-celis-video-adonde-va-el-dinero-del-boxeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fajador.com\/es\/inicio-incumplimiento\/"},{"@type":"ListItem","position":2,"name":"Ricardo Celis (V\u00eddeo): \u00ab\u00bfAd\u00f3nde va el dinero del boxeo?\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/fajador.com\/es\/#website","url":"https:\/\/fajador.com\/es\/","name":"Fajador","description":"MMAFighting.com, MMAJunkie.com","publisher":{"@id":"https:\/\/fajador.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fajador.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fajador.com\/es\/#organization","name":"Fajador","url":"https:\/\/fajador.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fajador.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fajador.com\/wp-content\/uploads\/2024\/05\/download.png","contentUrl":"https:\/\/fajador.com\/wp-content\/uploads\/2024\/05\/download.png","width":1949,"height":889,"caption":"Fajador"},"image":{"@id":"https:\/\/fajador.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/FajadorMedia","https:\/\/www.youtube.com\/channel\/UCJTdJHPyJbfRNKOeCd_O-Bw","https:\/\/www.instagram.com\/fajadormedia\/"]},{"@type":"Person","@id":"https:\/\/fajador.com\/es\/#\/schema\/person\/e9db63ee9447a5ddb11c95253ed203f3","name":"Fajador Noticias","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ba5d64466b624cbe3591dc01ffc4978fdb6859827f3e152ee9a8625fd00a2cea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba5d64466b624cbe3591dc01ffc4978fdb6859827f3e152ee9a8625fd00a2cea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba5d64466b624cbe3591dc01ffc4978fdb6859827f3e152ee9a8625fd00a2cea?s=96&d=mm&r=g","caption":"Fajador Noticias"},"sameAs":["http:\/\/fajador.com","https:\/\/www.facebook.com\/p\/Fajador-61566924322340\/","https:\/\/www.instagram.com\/fajadormedia\/?hl=en"],"url":"https:\/\/fajador.com\/es\/author\/fajador-noticias\/"}]}},"_links":{"self":[{"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/posts\/23812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/users\/870"}],"replies":[{"embeddable":true,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/comments?post=23812"}],"version-history":[{"count":2,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/posts\/23812\/revisions"}],"predecessor-version":[{"id":23820,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/posts\/23812\/revisions\/23820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/media\/23813"}],"wp:attachment":[{"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/media?parent=23812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/categories?post=23812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fajador.com\/es\/wp-json\/wp\/v2\/tags?post=23812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a7dcc8f46fa5ca62c0d9fc3. Config Timestamp: 2026-08-13 13:54:22 UTC, Cached Timestamp: 2026-09-02 07:56:50 UTC -->